{"id":4476,"date":"2016-01-16T02:06:50","date_gmt":"2016-01-16T01:06:50","guid":{"rendered":"http:\/\/www.madridsensations.com\/es\/?p=4476"},"modified":"2020-05-26T16:07:10","modified_gmt":"2020-05-26T14:07:10","slug":"6-lugares-unesco-alrededor-de-madrid","status":"publish","type":"post","link":"https:\/\/madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/","title":{"rendered":"6 tesoros UNESCO cerca de Madrid"},"content":{"rendered":"<p>Madrid es la capital de Espa\u00f1a \u00abtan solo\u00bb desde el siglo XVI, antes de eso era una villa relativamente peque\u00f1a, pero con\u00a0una localizaci\u00f3n estrat\u00e9gica. Por ello hoy la historia nos deja <em>grandes joyas alrededor de Madrid<\/em>. Y as\u00ed tenemos 6 bienes\u00a0que pertenecen al <em><a href=\"http:\/\/portal.unesco.org\/es\/ev.php-URL_ID=45692&amp;URL_DO=DO_TOPIC&amp;URL_SECTION=201.html\">Patrimonio de la Humanidad de la UNESCO<\/a><\/em>, a aproximadamente\u00a0de una hora en coche desde Madrid, ideal para una excursi\u00f3n en el d\u00eda.<\/p>\n<h3>Paisaje Cultural de Aranjuez<\/h3>\n<p>El primer tren de Madrid conectaba con Aranjuez desde la <a href=\"https:\/\/madridsensations.com\/es\/estacion-de-atocha\/\">Estaci\u00f3n de Atocha<\/a>, para disfrute de Isabel II que ten\u00eda all\u00ed uno de sus magn\u00edficos palacios. Hoy los madrile\u00f1os lo tenemos f\u00e1cil para visitarlo, siendo parte del patrimonio de la UNESCO gracias entre otras cosas a sus jardines.<\/p>\n<p><strong><em><a href=\"https:\/\/madridsensations.com\/es\/aranjuez\/\">\u00bfQu\u00e9 ver en Aranjuez?<\/a><\/em><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3088\" src=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/08\/Palacio-Real-de-Aranjuez-2.jpg\" alt=\"Palacio Real de Aranjuez\" width=\"800\" height=\"346\" srcset=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/08\/Palacio-Real-de-Aranjuez-2.jpg 800w, https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/08\/Palacio-Real-de-Aranjuez-2-300x129.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3>Monasterio y Sitio de El Escorial en Madrid<\/h3>\n<p>El edificio no es solo un monasterio, ni solo un palacio, son muchas cosas, es tambi\u00e9n el pante\u00f3n de los reyes de Espa\u00f1a y un seminario. Lo bueno es que a nosotros no nos costar\u00e1 tanto llegar como a Felipe II, que en su \u00faltimo viaje, afectado por la gota, tard\u00f3 7 d\u00edas desde Madrid.<\/p>\n<p><strong><em><a href=\"https:\/\/madridsensations.com\/es\/el-escorial\/\">\u00bfQu\u00e9 ver en El Escorial?<\/a><\/em><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4368\" src=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2015\/09\/El-Escorial.jpg\" alt=\"El Escorial\" width=\"800\" height=\"446\" srcset=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2015\/09\/El-Escorial.jpg 800w, https:\/\/madridsensations.com\/wp-content\/uploads\/2015\/09\/El-Escorial-300x167.jpg 300w, https:\/\/madridsensations.com\/wp-content\/uploads\/2015\/09\/El-Escorial-357x200.jpg 357w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3>Universidad y barrio hist\u00f3rico de Alcal\u00e1 de Henares<\/h3>\n<p>Encantadora, tranquila y diversa. Tenemos para disfrutar desde las famosas tapas en la Calle Mayor hasta las ruinas romanas de Complutum, sin olvidar la casa de Cervantes y la universidad renacentista.<\/p>\n<p><strong><em><a href=\"https:\/\/madridsensations.com\/es\/que-ver-en-alcala-de-henares\/\">\u00bfQu\u00e9 ver en Alcal\u00e1 de Henares?<\/a><\/em><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2541\" src=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/04\/Tour-Alcala-de-Henares-Plaza-Cervantes-2.jpg\" alt=\"Plaza de Cervantes en Alcal\u00e1 de Henares\" width=\"800\" height=\"417\" srcset=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/04\/Tour-Alcala-de-Henares-Plaza-Cervantes-2.jpg 800w, https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/04\/Tour-Alcala-de-Henares-Plaza-Cervantes-2-300x156.jpg 300w, https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/04\/Tour-Alcala-de-Henares-Plaza-Cervantes-2-768x400.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3>Ciudad hist\u00f3rica de Toledo<\/h3>\n<p>La ciudad de las tres culturas es c\u00e9lebre en el mundo entero,\u00a0pocos lugares albergan tantos siglos de historia tan bien preservados. No basta con ir a visitarla una vez y cada vez que vayas descubrir\u00e1s algo nuevo. Los que somos all\u00ed gu\u00edas de turismo no dejamos de sorprendernos y enamorarnos cada d\u00eda un poco m\u00e1s.<\/p>\n<p><strong><em><a href=\"https:\/\/madridsensations.com\/es\/visitar-toledo\/\">\u00bfQu\u00e9 ver en Toledo?<\/a><\/em><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4481\" src=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2016\/01\/Vistas-de-Toledo.jpg\" alt=\"Vistas de Toledo\" width=\"800\" height=\"450\" srcset=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2016\/01\/Vistas-de-Toledo.jpg 800w, https:\/\/madridsensations.com\/wp-content\/uploads\/2016\/01\/Vistas-de-Toledo-300x169.jpg 300w, https:\/\/madridsensations.com\/wp-content\/uploads\/2016\/01\/Vistas-de-Toledo-768x432.jpg 768w, https:\/\/madridsensations.com\/wp-content\/uploads\/2016\/01\/Vistas-de-Toledo-357x200.jpg 357w, https:\/\/madridsensations.com\/wp-content\/uploads\/2016\/01\/Vistas-de-Toledo-150x84.jpg 150w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3>Ciudad vieja y acueducto de Segovia<\/h3>\n<p>Solo el acueducto\u00a0(del siglo I) es una joya sin igual, pero es que adem\u00e1s el Alcazar es de cuento y su catedral una dama elegante y fina&#8230; De modo que si eres madrile\u00f1o y nunca has comido cochinillo en Segovia, es que o eres vegetariano o tienes una cita pendiente.<\/p>\n<p><strong><em><a href=\"https:\/\/madridsensations.com\/es\/visitar-segovia\/\">\u00bfQu\u00e9 ver en Segovia?<\/a><\/em><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2918 size-full\" src=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-3.jpg\" alt=\"Segovia (3)\" width=\"800\" height=\"486\" srcset=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-3.jpg 800w, https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-3-300x182.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3>Ciudad vieja de \u00c1vila e Iglesias extramuros<\/h3>\n<p>Sus murallas son icono de la edad media castellana y el interior de la catedral es un bello rinc\u00f3n poco conocido. \u00c1vila es tambi\u00e9n famosa por su gastronom\u00eda y por Santa Teresa de Jes\u00fas, muy presente en cada rinc\u00f3n de la ciudad.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4480\" src=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2016\/01\/Murallas-de-Avila.jpg\" alt=\"Murallas de \u00c1vila\" width=\"800\" height=\"450\" srcset=\"https:\/\/madridsensations.com\/wp-content\/uploads\/2016\/01\/Murallas-de-Avila.jpg 800w, https:\/\/madridsensations.com\/wp-content\/uploads\/2016\/01\/Murallas-de-Avila-300x169.jpg 300w, https:\/\/madridsensations.com\/wp-content\/uploads\/2016\/01\/Murallas-de-Avila-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2>Tours Privados desde Madrid<\/h2>\n<p>Si quiere visitar alguna de estas ciudades con un gu\u00eda oficial de turismo, le proponemos nuestras <a href=\"https:\/\/madridsensations.com\/es\/tour-privado-madrid\/\">excursiones desde Madrid<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid es la capital de Espa\u00f1a \u00abtan solo\u00bb desde el siglo XVI, antes de eso era una villa relativamente peque\u00f1a, pero con\u00a0una localizaci\u00f3n estrat\u00e9gica. Por ello hoy la historia nos deja grandes joyas alrededor de Madrid. Y as\u00ed tenemos 6 bienes\u00a0que pertenecen al Patrimonio de la Humanidad de la UNESCO, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2920,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[28],"tags":[561,559,560,562,558,84,38],"class_list":["post-4476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alrededor-de-madrid","tag-alcala","tag-aranjuez","tag-avila","tag-escorial","tag-segovia","tag-toledo","tag-unesco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>6 tesoros UNESCO cerca de Madrid - Madrid Sensations Tours<\/title>\n<meta name=\"description\" content=\"Lista de los\u00a06 lugares Patrimonio de la Humanidad de la UNESCO alrededor de Madrid: Segovia, \u00c1vila, Escorial, Toledo, Aranjuez y Alcal\u00e1 de Henares.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 tesoros UNESCO cerca de Madrid\" \/>\n<meta property=\"og:description\" content=\"Lista de los\u00a06 lugares Patrimonio de la Humanidad de la UNESCO alrededor de Madrid: Segovia, \u00c1vila, Escorial, Toledo, Aranjuez y Alcal\u00e1 de Henares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Madrid Sensations Tours\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madridsensations\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-16T01:06:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-26T14:07:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"6 tesoros UNESCO cerca de Madrid\",\"datePublished\":\"2016-01-16T01:06:50+00:00\",\"dateModified\":\"2020-05-26T14:07:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/madridsensations.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-1.jpg\",\"keywords\":[\"Alcala\",\"Aranjuez\",\"Avila\",\"Escorial\",\"Segovia\",\"Toledo\",\"UNESCO\"],\"articleSection\":[\"Excursiones cerca de Madrid\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/\",\"url\":\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/\",\"name\":\"6 tesoros UNESCO cerca de Madrid - Madrid Sensations Tours\",\"isPartOf\":{\"@id\":\"https:\/\/madridsensations.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-1.jpg\",\"datePublished\":\"2016-01-16T01:06:50+00:00\",\"dateModified\":\"2020-05-26T14:07:10+00:00\",\"description\":\"Lista de los\u00a06 lugares Patrimonio de la Humanidad de la UNESCO alrededor de Madrid: Segovia, \u00c1vila, Escorial, Toledo, Aranjuez y Alcal\u00e1 de Henares.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#primaryimage\",\"url\":\"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-1.jpg\",\"contentUrl\":\"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-1.jpg\",\"width\":800,\"height\":513},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/madridsensations.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"6 tesoros UNESCO cerca de Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/madridsensations.com\/es\/#website\",\"url\":\"https:\/\/madridsensations.com\/es\/\",\"name\":\"Madrid Sensations Tours\",\"description\":\"Explore and Discover Madrid with a private tour!\",\"publisher\":{\"@id\":\"https:\/\/madridsensations.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/madridsensations.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/madridsensations.com\/es\/#organization\",\"name\":\"Madrid Sensations Tours\",\"url\":\"https:\/\/madridsensations.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/madridsensations.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.madridsensations.com\/wp-content\/uploads\/2020\/04\/Logo-Madrid-Sensations.png\",\"contentUrl\":\"https:\/\/www.madridsensations.com\/wp-content\/uploads\/2020\/04\/Logo-Madrid-Sensations.png\",\"width\":3377,\"height\":3377,\"caption\":\"Madrid Sensations Tours\"},\"image\":{\"@id\":\"https:\/\/madridsensations.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/madridsensations\/\",\"https:\/\/x.com\/MadridSnsations\",\"https:\/\/www.instagram.com\/madridsensations\/\",\"https:\/\/www.linkedin.com\/company\/2560011\/\",\"https:\/\/www.pinterest.es\/madridsensation\",\"https:\/\/www.youtube.com\/c\/Madridsensations\"]},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"6 tesoros UNESCO cerca de Madrid - Madrid Sensations Tours","description":"Lista de los\u00a06 lugares Patrimonio de la Humanidad de la UNESCO alrededor de Madrid: Segovia, \u00c1vila, Escorial, Toledo, Aranjuez y Alcal\u00e1 de Henares.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/","og_locale":"es_ES","og_type":"article","og_title":"6 tesoros UNESCO cerca de Madrid","og_description":"Lista de los\u00a06 lugares Patrimonio de la Humanidad de la UNESCO alrededor de Madrid: Segovia, \u00c1vila, Escorial, Toledo, Aranjuez y Alcal\u00e1 de Henares.","og_url":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/","og_site_name":"Madrid Sensations Tours","article_publisher":"https:\/\/www.facebook.com\/madridsensations\/","article_published_time":"2016-01-16T01:06:50+00:00","article_modified_time":"2020-05-26T14:07:10+00:00","og_image":[{"width":800,"height":513,"url":"https:\/\/www.madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-1.jpg","type":"image\/jpeg"}],"twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#article","isPartOf":{"@id":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/"},"author":{"name":"","@id":""},"headline":"6 tesoros UNESCO cerca de Madrid","datePublished":"2016-01-16T01:06:50+00:00","dateModified":"2020-05-26T14:07:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/madridsensations.com\/es\/#organization"},"image":{"@id":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-1.jpg","keywords":["Alcala","Aranjuez","Avila","Escorial","Segovia","Toledo","UNESCO"],"articleSection":["Excursiones cerca de Madrid"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/","url":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/","name":"6 tesoros UNESCO cerca de Madrid - Madrid Sensations Tours","isPartOf":{"@id":"https:\/\/madridsensations.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#primaryimage"},"image":{"@id":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-1.jpg","datePublished":"2016-01-16T01:06:50+00:00","dateModified":"2020-05-26T14:07:10+00:00","description":"Lista de los\u00a06 lugares Patrimonio de la Humanidad de la UNESCO alrededor de Madrid: Segovia, \u00c1vila, Escorial, Toledo, Aranjuez y Alcal\u00e1 de Henares.","breadcrumb":{"@id":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#primaryimage","url":"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-1.jpg","contentUrl":"https:\/\/madridsensations.com\/wp-content\/uploads\/2013\/06\/Segovia-1.jpg","width":800,"height":513},{"@type":"BreadcrumbList","@id":"https:\/\/www.madridsensations.com\/es\/6-lugares-unesco-alrededor-de-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/madridsensations.com\/es\/"},{"@type":"ListItem","position":2,"name":"6 tesoros UNESCO cerca de Madrid"}]},{"@type":"WebSite","@id":"https:\/\/madridsensations.com\/es\/#website","url":"https:\/\/madridsensations.com\/es\/","name":"Madrid Sensations Tours","description":"Explore and Discover Madrid with a private tour!","publisher":{"@id":"https:\/\/madridsensations.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madridsensations.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/madridsensations.com\/es\/#organization","name":"Madrid Sensations Tours","url":"https:\/\/madridsensations.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/madridsensations.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.madridsensations.com\/wp-content\/uploads\/2020\/04\/Logo-Madrid-Sensations.png","contentUrl":"https:\/\/www.madridsensations.com\/wp-content\/uploads\/2020\/04\/Logo-Madrid-Sensations.png","width":3377,"height":3377,"caption":"Madrid Sensations Tours"},"image":{"@id":"https:\/\/madridsensations.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/madridsensations\/","https:\/\/x.com\/MadridSnsations","https:\/\/www.instagram.com\/madridsensations\/","https:\/\/www.linkedin.com\/company\/2560011\/","https:\/\/www.pinterest.es\/madridsensation","https:\/\/www.youtube.com\/c\/Madridsensations"]},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/madridsensations.com\/es\/wp-json\/wp\/v2\/posts\/4476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madridsensations.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/madridsensations.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/madridsensations.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/madridsensations.com\/es\/wp-json\/wp\/v2\/comments?post=4476"}],"version-history":[{"count":0,"href":"https:\/\/madridsensations.com\/es\/wp-json\/wp\/v2\/posts\/4476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/madridsensations.com\/es\/wp-json\/wp\/v2\/media\/2920"}],"wp:attachment":[{"href":"https:\/\/madridsensations.com\/es\/wp-json\/wp\/v2\/media?parent=4476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/madridsensations.com\/es\/wp-json\/wp\/v2\/categories?post=4476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/madridsensations.com\/es\/wp-json\/wp\/v2\/tags?post=4476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}